{"id":4330,"date":"2020-12-15T10:36:50","date_gmt":"2020-12-15T10:36:50","guid":{"rendered":"https:\/\/pawel.stefanoff.pl\/work\/?post_type=publikacje&#038;p=4330"},"modified":"2026-04-23T14:48:05","modified_gmt":"2026-04-23T14:48:05","slug":"article-2020-reporting-during-covid-es","status":"publish","type":"publikacje","link":"https:\/\/pawel.stefanoff.pl\/work\/es\/articles\/article-2020-reporting-during-covid-es\/","title":{"rendered":"Notificaci\u00f3n de enfermedades infecciosas de declaraci\u00f3n obligatoria durante la respuesta a la COVID-19"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El art\u00edculo examina c\u00f3mo las medidas implementadas para controlar la COVID-19 en Noruega \u2014como el distanciamiento social y la ampliaci\u00f3n de las pruebas\u2014 se asociaron con una marcada reducci\u00f3n en la notificaci\u00f3n de otras enfermedades infecciosas. En los primeros meses de 2020, los datos de vigilancia mostraron una clara disminuci\u00f3n en los casos notificados de varias enfermedades transmisibles en comparaci\u00f3n con a\u00f1os anteriores. Esta reducci\u00f3n puede reflejar una menor transmisi\u00f3n como resultado de las medidas de distanciamiento social, pero tambi\u00e9n podr\u00eda explicarse en parte por la reasignaci\u00f3n de recursos sanitarios hacia el manejo de la COVID-19. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estoy particularmente orgulloso de esta publicaci\u00f3n, ya que fue mi primer art\u00edculo cient\u00edfico escrito en noruego. Si bien la Revista de la Asociaci\u00f3n M\u00e9dica Noruega se publica tanto en noruego como en ingl\u00e9s, la versi\u00f3n en ingl\u00e9s es una traducci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo en noruego e ingl\u00e9s publicado en la revista Tidsskrift for Den norske legeforening<\/p>\n","protected":false},"featured_media":687,"template":"","meta":{"_acf_changed":true},"class_list":["post-4330","publikacje","type-publikacje","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje\/4330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje"}],"about":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/types\/publikacje"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media\/687"}],"wp:attachment":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media?parent=4330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}