{"id":4344,"date":"2018-09-01T12:12:20","date_gmt":"2018-09-01T12:12:20","guid":{"rendered":"https:\/\/pawel.stefanoff.pl\/work\/?post_type=publikacje&#038;p=4344"},"modified":"2026-04-25T09:08:08","modified_gmt":"2026-04-25T09:08:08","slug":"article-2018-tbe-model-es","status":"publish","type":"publikacje","link":"https:\/\/pawel.stefanoff.pl\/work\/es\/articles\/article-2018-tbe-model-es\/","title":{"rendered":"Un modelo predictivo ha identificado zonas de alto riesgo de encefalitis transmitida por garrapatas en regiones donde no se hab\u00edan notificado casos previamente, Polonia, 1999-2012"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El art\u00edculo presenta un modelo predictivo para identificar \u00e1reas con alto riesgo de encefalitis transmitida por garrapatas (ETG) en Polonia. Mediante una combinaci\u00f3n de factores meteorol\u00f3gicos, ambientales y socioecon\u00f3micos, el modelo identific\u00f3 regiones con riesgo elevado de ETG, incluyendo \u00e1reas donde no se hab\u00edan reportado casos previamente. Se encontr\u00f3 que las temperaturas m\u00e1s altas, el aumento de las precipitaciones y la proximidad a \u00e1reas boscosas fueron factores clave asociados con un mayor riesgo de ETG. El estudio sugiere que aumentar la concienciaci\u00f3n entre los m\u00e9dicos en estas regiones de alto riesgo y mejorar el acceso a las pruebas de diagn\u00f3stico podr\u00edan fortalecer la vigilancia y la prevenci\u00f3n de la enfermedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este an\u00e1lisis marc\u00f3 la culminaci\u00f3n de casi una d\u00e9cada de trabajo interdisciplinario que incluy\u00f3 una recopilaci\u00f3n de datos, colaboraci\u00f3n de expertos y numerosos debates. El modelo incorpor\u00f3 los mejores datos disponibles con la resoluci\u00f3n m\u00e1s fina posible (NUTS-5). Las variables meteorol\u00f3gicas fueron desarrolladas mediante m\u00e9todos de interpolaci\u00f3n espacial por el profesor Ustrnul y su equipo. Las variables de uso del suelo fueron preparadas por el ge\u00f3grafo Jakub Bratkowski a partir de datos del proyecto europeo CORINE Land Cover 2006, mientras que los datos socioecon\u00f3micos restantes se obtuvieron de la Oficina Central de Estad\u00edstica. El modelo predictivo fue desarrollado por la estudiante de matem\u00e1ticas Basia Rubikowska y supervisado por la brillante estad\u00edstica Magda Rosi\u0144ska. Esper\u00e1bamos que este enfoque de modelado se adoptar\u00e1 de forma m\u00e1s habitual en las instituciones nacionales de salud p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo en ingl\u00e9s publicado en la revista International Journal of Environmental Research and Public Health<\/p>\n","protected":false},"featured_media":687,"template":"","meta":{"_acf_changed":false},"class_list":["post-4344","publikacje","type-publikacje","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje\/4344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje"}],"about":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/types\/publikacje"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media\/687"}],"wp:attachment":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media?parent=4344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}