{"id":4367,"date":"2013-07-15T11:02:02","date_gmt":"2013-07-15T11:02:02","guid":{"rendered":"https:\/\/pawel.stefanoff.pl\/work\/?post_type=publikacje&#038;p=4367"},"modified":"2026-04-23T15:05:22","modified_gmt":"2026-04-23T15:05:22","slug":"article-2013-agi-costs-es","status":"publish","type":"publikacje","link":"https:\/\/pawel.stefanoff.pl\/work\/es\/articles\/article-2013-agi-costs-es\/","title":{"rendered":"Costos de las infecciones gastrointestinales agudas que requieren atenci\u00f3n m\u00e9dica: la encuesta prospectiva sobre la utilizaci\u00f3n de los recursos sanitarios en Polonia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El art\u00edculo explor\u00f3 la carga econ\u00f3mica de las infecciones gastrointestinales agudas (GEA) en Polonia. Demostr\u00f3 que, si bien el costo del tratamiento de un caso individual de GEA era relativamente bajo, el impacto social general era sustancial, principalmente debido a costos indirectos como la p\u00e9rdida de productividad. El estudio estim\u00f3 que el costo social de los casos de GEA atendidos m\u00e9dicamente ascend\u00eda a aproximadamente 2200 millones de d\u00f3lares anuales, de los cuales el 53 % correspond\u00eda a costos indirectos. Los hallazgos sugirieron que se deber\u00edan haber asignado mayores recursos a la prevenci\u00f3n y el control de las GEA para reducir su impacto econ\u00f3mico en la sociedad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El an\u00e1lisis combin\u00f3 informaci\u00f3n recopilada de m\u00faltiples estudios observacionales realizados en paralelo durante a\u00f1os anteriores. Contamos con la participaci\u00f3n del economista de la salud Marcin Czech, a quien conocimos en algunos cursos y reuniones oficiales, y que m\u00e1s tarde se convirti\u00f3 en viceministro de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo en ingl\u00e9s publicado en la revista Value in Health Regional Issues<\/p>\n","protected":false},"featured_media":1074,"template":"","meta":{"_acf_changed":true},"class_list":["post-4367","publikacje","type-publikacje","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje\/4367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje"}],"about":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/types\/publikacje"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media\/1074"}],"wp:attachment":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media?parent=4367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}