{"id":4377,"date":"2012-05-01T11:27:10","date_gmt":"2012-05-01T11:27:10","guid":{"rendered":"https:\/\/pawel.stefanoff.pl\/work\/?post_type=publikacje&#038;p=4377"},"modified":"2026-04-23T17:35:40","modified_gmt":"2026-04-23T17:35:40","slug":"article-2012-influenza-policies-es","status":"publish","type":"publikacje","link":"https:\/\/pawel.stefanoff.pl\/work\/es\/articles\/article-2012-influenza-policies-es\/","title":{"rendered":"Recomendaciones y cobertura de vacunaci\u00f3n contra la influenza A(H1N1)pdm09 en Europa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante la pandemia de gripe H1N1 de 2009, la mayor\u00eda de los pa\u00edses de la Uni\u00f3n Europea, junto con Noruega e Islandia, implementaron campa\u00f1as nacionales de vacunaci\u00f3n dirigidas a trabajadores sanitarios, mujeres embarazadas y personas con enfermedades cr\u00f3nicas, siguiendo las recomendaciones internacionales. Algunos pa\u00edses ampliaron la vacunaci\u00f3n a otros grupos de edad o profesionales. A pesar de las estrategias similares, la cobertura de vacunaci\u00f3n vari\u00f3 considerablemente, desde menos del 1 % hasta casi el 60 %. Estas diferencias se debieron a la preocupaci\u00f3n p\u00fablica por la seguridad de las vacunas, la confianza en la vacunaci\u00f3n, la comunicaci\u00f3n y las limitaciones log\u00edsticas. Los resultados sugieren que unos sistemas de vigilancia m\u00e1s s\u00f3lidos y una comunicaci\u00f3n m\u00e1s clara podr\u00edan mejorar la vacunaci\u00f3n en futuras pandemias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta revisi\u00f3n form\u00f3 parte del proyecto VENICE-2, que recopil\u00f3 datos sobre programas de inmunizaci\u00f3n en los pa\u00edses de la UE en nombre del Centro Europeo para la Prevenci\u00f3n y el Control de Enfermedades (ECDC). Colabor\u00e9 en la recopilaci\u00f3n de datos de algunos pa\u00edses y revis\u00e9 el art\u00edculo, pero la mayor parte del trabajo la realiz\u00f3 Jolita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo en ingl\u00e9s publicado en la revista Eurosurveillance<\/p>\n","protected":false},"featured_media":1074,"template":"","meta":{"_acf_changed":false},"class_list":["post-4377","publikacje","type-publikacje","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje\/4377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/publikacje"}],"about":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/types\/publikacje"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media\/1074"}],"wp:attachment":[{"href":"https:\/\/pawel.stefanoff.pl\/work\/wp-json\/wp\/v2\/media?parent=4377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}